{"id":2018,"count":1,"description":"","link":"https:\/\/linnaclinic.com\/en\/diagnostic-methods\/immunofluorescence-assay-ifa\/","name":"Immunofluorescence Assay (IFA)","slug":"immunofluorescence-assay-ifa","taxonomy":"diagnostic-methods","meta":[],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Immunofluorescence Assay (IFA)\u5f52\u6863 - LINNA CLINIC<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/linnaclinic.com\/zh-hans\/diagnostic-methods\/immunofluorescence-assay-ifa\/\" \/>\n<meta property=\"og:locale\" content=\"zh_CN\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Immunofluorescence Assay (IFA)\u5f52\u6863 - LINNA CLINIC\" \/>\n<meta property=\"og:url\" content=\"https:\/\/linnaclinic.com\/en\/diagnostic-methods\/immunofluorescence-assay-ifa\/\" \/>\n<meta property=\"og:site_name\" content=\"LINNA CLINIC\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/linnaclinic.com\\\/en\\\/diagnostic-methods\\\/immunofluorescence-assay-ifa\\\/\",\"url\":\"https:\\\/\\\/linnaclinic.com\\\/en\\\/diagnostic-methods\\\/immunofluorescence-assay-ifa\\\/\",\"name\":\"Immunofluorescence Assay (IFA)\u5f52\u6863 - LINNA CLINIC\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/linnaclinic.com\\\/zh-hans\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/linnaclinic.com\\\/en\\\/diagnostic-methods\\\/immunofluorescence-assay-ifa\\\/#breadcrumb\"},\"inLanguage\":\"zh-Hans\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/linnaclinic.com\\\/en\\\/diagnostic-methods\\\/immunofluorescence-assay-ifa\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/linnaclinic.com\\\/zh-hans\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Immunofluorescence Assay (IFA)\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/linnaclinic.com\\\/zh-hans\\\/#website\",\"url\":\"https:\\\/\\\/linnaclinic.com\\\/zh-hans\\\/\",\"name\":\"LINNA CLINIC\",\"description\":\"LINNA CLINIC\",\"publisher\":{\"@id\":\"https:\\\/\\\/linnaclinic.com\\\/zh-hans\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/linnaclinic.com\\\/zh-hans\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"zh-Hans\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/linnaclinic.com\\\/zh-hans\\\/#organization\",\"name\":\"LINNA CLINIC\",\"url\":\"https:\\\/\\\/linnaclinic.com\\\/zh-hans\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"zh-Hans\",\"@id\":\"https:\\\/\\\/linnaclinic.com\\\/zh-hans\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/linnaclinic.com\\\/wp-content\\\/uploads\\\/2021\\\/04\\\/LNNA-scaled.webp\",\"contentUrl\":\"https:\\\/\\\/linnaclinic.com\\\/wp-content\\\/uploads\\\/2021\\\/04\\\/LNNA-scaled.webp\",\"width\":2560,\"height\":843,\"caption\":\"LINNA CLINIC\"},\"image\":{\"@id\":\"https:\\\/\\\/linnaclinic.com\\\/zh-hans\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Immunofluorescence Assay (IFA)\u5f52\u6863 - LINNA CLINIC","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/linnaclinic.com\/zh-hans\/diagnostic-methods\/immunofluorescence-assay-ifa\/","og_locale":"zh_CN","og_type":"article","og_title":"Immunofluorescence Assay (IFA)\u5f52\u6863 - LINNA CLINIC","og_url":"https:\/\/linnaclinic.com\/en\/diagnostic-methods\/immunofluorescence-assay-ifa\/","og_site_name":"LINNA CLINIC","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/linnaclinic.com\/en\/diagnostic-methods\/immunofluorescence-assay-ifa\/","url":"https:\/\/linnaclinic.com\/en\/diagnostic-methods\/immunofluorescence-assay-ifa\/","name":"Immunofluorescence Assay (IFA)\u5f52\u6863 - LINNA CLINIC","isPartOf":{"@id":"https:\/\/linnaclinic.com\/zh-hans\/#website"},"breadcrumb":{"@id":"https:\/\/linnaclinic.com\/en\/diagnostic-methods\/immunofluorescence-assay-ifa\/#breadcrumb"},"inLanguage":"zh-Hans"},{"@type":"BreadcrumbList","@id":"https:\/\/linnaclinic.com\/en\/diagnostic-methods\/immunofluorescence-assay-ifa\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/linnaclinic.com\/zh-hans\/"},{"@type":"ListItem","position":2,"name":"Immunofluorescence Assay (IFA)"}]},{"@type":"WebSite","@id":"https:\/\/linnaclinic.com\/zh-hans\/#website","url":"https:\/\/linnaclinic.com\/zh-hans\/","name":"LINNA CLINIC","description":"LINNA CLINIC","publisher":{"@id":"https:\/\/linnaclinic.com\/zh-hans\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/linnaclinic.com\/zh-hans\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"zh-Hans"},{"@type":"Organization","@id":"https:\/\/linnaclinic.com\/zh-hans\/#organization","name":"LINNA CLINIC","url":"https:\/\/linnaclinic.com\/zh-hans\/","logo":{"@type":"ImageObject","inLanguage":"zh-Hans","@id":"https:\/\/linnaclinic.com\/zh-hans\/#\/schema\/logo\/image\/","url":"https:\/\/linnaclinic.com\/wp-content\/uploads\/2021\/04\/LNNA-scaled.webp","contentUrl":"https:\/\/linnaclinic.com\/wp-content\/uploads\/2021\/04\/LNNA-scaled.webp","width":2560,"height":843,"caption":"LINNA CLINIC"},"image":{"@id":"https:\/\/linnaclinic.com\/zh-hans\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/linnaclinic.com\/zh-hans\/wp-json\/wp\/v2\/diagnostic-methods\/2018","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/linnaclinic.com\/zh-hans\/wp-json\/wp\/v2\/diagnostic-methods"}],"about":[{"href":"https:\/\/linnaclinic.com\/zh-hans\/wp-json\/wp\/v2\/taxonomies\/diagnostic-methods"}],"wp:post_type":[{"href":"https:\/\/linnaclinic.com\/zh-hans\/wp-json\/wp\/v2\/product?diagnostic-methods=2018"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}