{"id":1500,"count":4,"description":"","link":"https:\/\/linnaclinic.com\/en\/diagnostic-methods\/pcr-rflp\/","name":"PCR-RFLP","slug":"pcr-rflp","taxonomy":"diagnostic-methods","meta":[],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>PCR-RFLP Archives - LINNA CLINIC<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/linnaclinic.com\/en\/diagnostic-methods\/pcr-rflp\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"PCR-RFLP Archives - LINNA CLINIC\" \/>\n<meta property=\"og:url\" content=\"https:\/\/linnaclinic.com\/en\/diagnostic-methods\/pcr-rflp\/\" \/>\n<meta property=\"og:site_name\" content=\"LINNA CLINIC\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/linnaclinic.com\\\/en\\\/diagnostic-methods\\\/pcr-rflp\\\/\",\"url\":\"https:\\\/\\\/linnaclinic.com\\\/en\\\/diagnostic-methods\\\/pcr-rflp\\\/\",\"name\":\"PCR-RFLP Archives - LINNA CLINIC\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/linnaclinic.com\\\/en\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/linnaclinic.com\\\/en\\\/diagnostic-methods\\\/pcr-rflp\\\/#breadcrumb\"},\"inLanguage\":\"en-US\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/linnaclinic.com\\\/en\\\/diagnostic-methods\\\/pcr-rflp\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/linnaclinic.com\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"PCR-RFLP\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/linnaclinic.com\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/linnaclinic.com\\\/en\\\/\",\"name\":\"LINNA CLINIC\",\"description\":\"LINNA CLINIC\",\"publisher\":{\"@id\":\"https:\\\/\\\/linnaclinic.com\\\/en\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/linnaclinic.com\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/linnaclinic.com\\\/en\\\/#organization\",\"name\":\"LINNA CLINIC\",\"url\":\"https:\\\/\\\/linnaclinic.com\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/linnaclinic.com\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/linnaclinic.com\\\/wp-content\\\/uploads\\\/2021\\\/04\\\/LNNA-scaled.webp\",\"contentUrl\":\"https:\\\/\\\/linnaclinic.com\\\/wp-content\\\/uploads\\\/2021\\\/04\\\/LNNA-scaled.webp\",\"width\":2560,\"height\":843,\"caption\":\"LINNA CLINIC\"},\"image\":{\"@id\":\"https:\\\/\\\/linnaclinic.com\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"PCR-RFLP Archives - LINNA CLINIC","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/linnaclinic.com\/en\/diagnostic-methods\/pcr-rflp\/","og_locale":"en_US","og_type":"article","og_title":"PCR-RFLP Archives - LINNA CLINIC","og_url":"https:\/\/linnaclinic.com\/en\/diagnostic-methods\/pcr-rflp\/","og_site_name":"LINNA CLINIC","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/linnaclinic.com\/en\/diagnostic-methods\/pcr-rflp\/","url":"https:\/\/linnaclinic.com\/en\/diagnostic-methods\/pcr-rflp\/","name":"PCR-RFLP Archives - LINNA CLINIC","isPartOf":{"@id":"https:\/\/linnaclinic.com\/en\/#website"},"breadcrumb":{"@id":"https:\/\/linnaclinic.com\/en\/diagnostic-methods\/pcr-rflp\/#breadcrumb"},"inLanguage":"en-US"},{"@type":"BreadcrumbList","@id":"https:\/\/linnaclinic.com\/en\/diagnostic-methods\/pcr-rflp\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/linnaclinic.com\/en\/"},{"@type":"ListItem","position":2,"name":"PCR-RFLP"}]},{"@type":"WebSite","@id":"https:\/\/linnaclinic.com\/en\/#website","url":"https:\/\/linnaclinic.com\/en\/","name":"LINNA CLINIC","description":"LINNA CLINIC","publisher":{"@id":"https:\/\/linnaclinic.com\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/linnaclinic.com\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/linnaclinic.com\/en\/#organization","name":"LINNA CLINIC","url":"https:\/\/linnaclinic.com\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/linnaclinic.com\/en\/#\/schema\/logo\/image\/","url":"https:\/\/linnaclinic.com\/wp-content\/uploads\/2021\/04\/LNNA-scaled.webp","contentUrl":"https:\/\/linnaclinic.com\/wp-content\/uploads\/2021\/04\/LNNA-scaled.webp","width":2560,"height":843,"caption":"LINNA CLINIC"},"image":{"@id":"https:\/\/linnaclinic.com\/en\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/linnaclinic.com\/en\/wp-json\/wp\/v2\/diagnostic-methods\/1500","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/linnaclinic.com\/en\/wp-json\/wp\/v2\/diagnostic-methods"}],"about":[{"href":"https:\/\/linnaclinic.com\/en\/wp-json\/wp\/v2\/taxonomies\/diagnostic-methods"}],"wp:post_type":[{"href":"https:\/\/linnaclinic.com\/en\/wp-json\/wp\/v2\/product?diagnostic-methods=1500"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}