{"id":1308,"count":3,"description":"","link":"https:\/\/linnaclinic.com\/ar\/symptoms\/low-platelets\/","name":"Low Platelets","slug":"low-platelets","taxonomy":"symptoms","meta":[],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Low Platelets \u0627\u0644\u0623\u0631\u0634\u064a\u0641 - LINNA CLINIC<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/linnaclinic.com\/ar\/symptoms\/low-platelets\/\" \/>\n<meta property=\"og:locale\" content=\"ar_AR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Low Platelets \u0627\u0644\u0623\u0631\u0634\u064a\u0641 - LINNA CLINIC\" \/>\n<meta property=\"og:url\" content=\"https:\/\/linnaclinic.com\/ar\/symptoms\/low-platelets\/\" \/>\n<meta property=\"og:site_name\" content=\"LINNA CLINIC\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/linnaclinic.com\\\/ar\\\/symptoms\\\/low-platelets\\\/\",\"url\":\"https:\\\/\\\/linnaclinic.com\\\/ar\\\/symptoms\\\/low-platelets\\\/\",\"name\":\"Low Platelets \u0627\u0644\u0623\u0631\u0634\u064a\u0641 - LINNA CLINIC\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/linnaclinic.com\\\/ar\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/linnaclinic.com\\\/ar\\\/symptoms\\\/low-platelets\\\/#breadcrumb\"},\"inLanguage\":\"ar\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/linnaclinic.com\\\/ar\\\/symptoms\\\/low-platelets\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/linnaclinic.com\\\/ar\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Low Platelets\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/linnaclinic.com\\\/ar\\\/#website\",\"url\":\"https:\\\/\\\/linnaclinic.com\\\/ar\\\/\",\"name\":\"LINNA CLINIC\",\"description\":\"LINNA CLINIC\",\"publisher\":{\"@id\":\"https:\\\/\\\/linnaclinic.com\\\/ar\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/linnaclinic.com\\\/ar\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"ar\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/linnaclinic.com\\\/ar\\\/#organization\",\"name\":\"LINNA CLINIC\",\"url\":\"https:\\\/\\\/linnaclinic.com\\\/ar\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"ar\",\"@id\":\"https:\\\/\\\/linnaclinic.com\\\/ar\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/linnaclinic.com\\\/wp-content\\\/uploads\\\/2021\\\/04\\\/LNNA-scaled.webp\",\"contentUrl\":\"https:\\\/\\\/linnaclinic.com\\\/wp-content\\\/uploads\\\/2021\\\/04\\\/LNNA-scaled.webp\",\"width\":2560,\"height\":843,\"caption\":\"LINNA CLINIC\"},\"image\":{\"@id\":\"https:\\\/\\\/linnaclinic.com\\\/ar\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Low Platelets \u0627\u0644\u0623\u0631\u0634\u064a\u0641 - LINNA CLINIC","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/linnaclinic.com\/ar\/symptoms\/low-platelets\/","og_locale":"ar_AR","og_type":"article","og_title":"Low Platelets \u0627\u0644\u0623\u0631\u0634\u064a\u0641 - LINNA CLINIC","og_url":"https:\/\/linnaclinic.com\/ar\/symptoms\/low-platelets\/","og_site_name":"LINNA CLINIC","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/linnaclinic.com\/ar\/symptoms\/low-platelets\/","url":"https:\/\/linnaclinic.com\/ar\/symptoms\/low-platelets\/","name":"Low Platelets \u0627\u0644\u0623\u0631\u0634\u064a\u0641 - LINNA CLINIC","isPartOf":{"@id":"https:\/\/linnaclinic.com\/ar\/#website"},"breadcrumb":{"@id":"https:\/\/linnaclinic.com\/ar\/symptoms\/low-platelets\/#breadcrumb"},"inLanguage":"ar"},{"@type":"BreadcrumbList","@id":"https:\/\/linnaclinic.com\/ar\/symptoms\/low-platelets\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/linnaclinic.com\/ar\/"},{"@type":"ListItem","position":2,"name":"Low Platelets"}]},{"@type":"WebSite","@id":"https:\/\/linnaclinic.com\/ar\/#website","url":"https:\/\/linnaclinic.com\/ar\/","name":"LINNA CLINIC","description":"LINNA CLINIC","publisher":{"@id":"https:\/\/linnaclinic.com\/ar\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/linnaclinic.com\/ar\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"ar"},{"@type":"Organization","@id":"https:\/\/linnaclinic.com\/ar\/#organization","name":"LINNA CLINIC","url":"https:\/\/linnaclinic.com\/ar\/","logo":{"@type":"ImageObject","inLanguage":"ar","@id":"https:\/\/linnaclinic.com\/ar\/#\/schema\/logo\/image\/","url":"https:\/\/linnaclinic.com\/wp-content\/uploads\/2021\/04\/LNNA-scaled.webp","contentUrl":"https:\/\/linnaclinic.com\/wp-content\/uploads\/2021\/04\/LNNA-scaled.webp","width":2560,"height":843,"caption":"LINNA CLINIC"},"image":{"@id":"https:\/\/linnaclinic.com\/ar\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/linnaclinic.com\/ar\/wp-json\/wp\/v2\/symptoms\/1308","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/linnaclinic.com\/ar\/wp-json\/wp\/v2\/symptoms"}],"about":[{"href":"https:\/\/linnaclinic.com\/ar\/wp-json\/wp\/v2\/taxonomies\/symptoms"}],"wp:post_type":[{"href":"https:\/\/linnaclinic.com\/ar\/wp-json\/wp\/v2\/product?symptoms=1308"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}